{"id":24,"count":2,"description":"","link":"https:\/\/prijedorguide.com\/sr\/category\/tours-travel\/","name":"Tours &amp; Travel","slug":"tours-travel","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/prijedorguide.com\/sr\/wp-json\/wp\/v2\/categories\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prijedorguide.com\/sr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/prijedorguide.com\/sr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/prijedorguide.com\/sr\/wp-json\/wp\/v2\/posts?categories=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}